{"id":204,"date":"2016-05-10T13:30:19","date_gmt":"2016-05-10T11:30:19","guid":{"rendered":"http:\/\/edjhdcub.preview.infomaniak.com\/?page_id=204"},"modified":"2018-01-16T12:22:49","modified_gmt":"2018-01-16T11:22:49","slug":"ws42-k","status":"publish","type":"page","link":"https:\/\/www.cellarview.ch\/fr\/rack-noir\/ws42-k\/","title":{"rendered":"WS42-K"},"content":{"rendered":"<p>WS42-K <strong>(noir mat)<\/strong>\u00a0supports ont une capacit\u00e9 de 24 bouteilles.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-252 aligncenter\" src=\"http:\/\/www.cellarview.ch\/wp-content\/uploads\/2016\/05\/WS42-modifie.jpeg\" alt=\"\" width=\"147\" height=\"461\" srcset=\"https:\/\/www.cellarview.ch\/wp-content\/uploads\/2016\/05\/WS42-modifie.jpeg 210w, https:\/\/www.cellarview.ch\/wp-content\/uploads\/2016\/05\/WS42-modifie-96x300.jpeg 96w\" sizes=\"(max-width: 147px) 100vw, 147px\" \/><\/p>\n<p style=\"text-align: justify;\">Chaque support \u00e0 deux montants \u2013 un pour supporter la base et l\u2019autre le col de la bouteille. Ceux-ci sont fix\u00e9s individuellement dans le mur. Ces supports \u00e0 bouteilles sont facile d\u2019installation (3 vis dans chaque montant) et peuvent \u00eatre utilis\u00e9s pour stocker les bouteilles de vin dans n\u2019importe quel espace.<\/p>\n<p>Capacit\u00e9 : 24 bouteilles \/ 2 profondeurs<br \/>\nDimensions : H 122 x L 33 x P 21.5 cm<br \/>\nColoris : <strong>Noir mat<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>WS42-K (noir mat)\u00a0supports ont une capacit\u00e9 de 24 bouteilles. Chaque support \u00e0 deux montants \u2013 un pour supporter la base et l\u2019autre le col de la bouteille. Ceux-ci sont fix\u00e9s individuellement dans le mur. Ces supports \u00e0 bouteilles sont facile d\u2019installation (3 vis dans chaque montant) et peuvent \u00eatre utilis\u00e9s pour stocker les bouteilles de &hellip; <a href=\"https:\/\/www.cellarview.ch\/fr\/rack-noir\/ws42-k\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de <span class=\"screen-reader-text\">WS42-K<\/span><\/span>&nbsp;<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":24,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/pages\/204"}],"collection":[{"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/comments?post=204"}],"version-history":[{"count":8,"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/pages\/204\/revisions"}],"predecessor-version":[{"id":837,"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/pages\/204\/revisions\/837"}],"up":[{"embeddable":true,"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/pages\/24"}],"wp:attachment":[{"href":"https:\/\/www.cellarview.ch\/fr\/wp-json\/wp\/v2\/media?parent=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}